{"id":7076,"count":3,"description":"","link":"https:\/\/cinebeta.net\/ug\/director\/riley-flanagan\/","name":"Riley Flanagan","slug":"riley-flanagan","taxonomy":"dtdirector","meta":[],"_links":{"self":[{"href":"https:\/\/cinebeta.net\/ug\/wp-json\/wp\/v2\/dtdirector\/7076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cinebeta.net\/ug\/wp-json\/wp\/v2\/dtdirector"}],"about":[{"href":"https:\/\/cinebeta.net\/ug\/wp-json\/wp\/v2\/taxonomies\/dtdirector"}],"wp:post_type":[{"href":"https:\/\/cinebeta.net\/ug\/wp-json\/wp\/v2\/movies?dtdirector=7076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}