{"id":2978,"count":2,"description":"","link":"https:\/\/cinebeta.net\/ug\/director\/randall-wallace\/","name":"Randall Wallace","slug":"randall-wallace","taxonomy":"dtdirector","meta":[],"_links":{"self":[{"href":"https:\/\/cinebeta.net\/ug\/wp-json\/wp\/v2\/dtdirector\/2978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cinebeta.net\/ug\/wp-json\/wp\/v2\/dtdirector"}],"about":[{"href":"https:\/\/cinebeta.net\/ug\/wp-json\/wp\/v2\/taxonomies\/dtdirector"}],"wp:post_type":[{"href":"https:\/\/cinebeta.net\/ug\/wp-json\/wp\/v2\/movies?dtdirector=2978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}