{"id":2389,"count":7,"description":"","link":"https:\/\/cinebeta.net\/ug\/director\/ridley-scott\/","name":"Ridley Scott","slug":"ridley-scott","taxonomy":"dtdirector","meta":[],"_links":{"self":[{"href":"https:\/\/cinebeta.net\/ug\/wp-json\/wp\/v2\/dtdirector\/2389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cinebeta.net\/ug\/wp-json\/wp\/v2\/dtdirector"}],"about":[{"href":"https:\/\/cinebeta.net\/ug\/wp-json\/wp\/v2\/taxonomies\/dtdirector"}],"wp:post_type":[{"href":"https:\/\/cinebeta.net\/ug\/wp-json\/wp\/v2\/movies?dtdirector=2389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}