{"id":13847,"count":1,"description":"","link":"https:\/\/cinebeta.net\/ug\/director\/michael-nell\/","name":"Michael Nell","slug":"michael-nell","taxonomy":"dtdirector","meta":[],"_links":{"self":[{"href":"https:\/\/cinebeta.net\/ug\/wp-json\/wp\/v2\/dtdirector\/13847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cinebeta.net\/ug\/wp-json\/wp\/v2\/dtdirector"}],"about":[{"href":"https:\/\/cinebeta.net\/ug\/wp-json\/wp\/v2\/taxonomies\/dtdirector"}],"wp:post_type":[{"href":"https:\/\/cinebeta.net\/ug\/wp-json\/wp\/v2\/movies?dtdirector=13847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}